{"id":1141,"count":3,"description":"","link":"https:\/\/demo.dualcube.com\/moowoodle\/category\/plyas-media-ru\/620a-z-2\/","name":"620A Z","slug":"620a-z-2","taxonomy":"category","parent":1140,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/categories\/1141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/categories\/1140"}],"wp:post_type":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/posts?categories=1141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}