{"id":1188,"count":3,"description":"","link":"https:\/\/demo.dualcube.com\/moowoodle\/category\/beregaevo-ru\/750a-z\/","name":"750A Z","slug":"750a-z","taxonomy":"category","parent":1187,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/categories\/1188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/categories\/1187"}],"wp:post_type":[{"href":"https:\/\/demo.dualcube.com\/moowoodle\/wp-json\/wp\/v2\/posts?categories=1188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}